{"id":80,"count":10,"description":"","link":"https:\/\/maslabor.com\/es\/category\/press-release\/","name":"Comunicado de prensa","slug":"press-release","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Press Release Archives - m\u00e1sLabor<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maslabor.com\/es\/category\/press-release\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Press Release Archives - m\u00e1sLabor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maslabor.com\/es\/category\/press-release\/\" \/>\n<meta property=\"og:site_name\" content=\"m\u00e1sLabor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/maslabor.com\\\/category\\\/press-release\\\/\",\"url\":\"https:\\\/\\\/maslabor.com\\\/category\\\/press-release\\\/\",\"name\":\"Press Release Archives - m\u00e1sLabor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maslabor.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maslabor.com\\\/category\\\/press-release\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maslabor.com\\\/category\\\/press-release\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/maslabor.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Press Release\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maslabor.com\\\/#website\",\"url\":\"https:\\\/\\\/maslabor.com\\\/\",\"name\":\"m\u00e1sLabor\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maslabor.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Press Release Archives - m\u00e1sLabor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maslabor.com\/es\/category\/press-release\/","og_locale":"es_ES","og_type":"article","og_title":"Press Release Archives - m\u00e1sLabor","og_url":"https:\/\/maslabor.com\/es\/category\/press-release\/","og_site_name":"m\u00e1sLabor","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/maslabor.com\/category\/press-release\/","url":"https:\/\/maslabor.com\/category\/press-release\/","name":"Press Release Archives - m\u00e1sLabor","isPartOf":{"@id":"https:\/\/maslabor.com\/#website"},"breadcrumb":{"@id":"https:\/\/maslabor.com\/category\/press-release\/#breadcrumb"},"inLanguage":"es-ES"},{"@type":"BreadcrumbList","@id":"https:\/\/maslabor.com\/category\/press-release\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/maslabor.com\/"},{"@type":"ListItem","position":2,"name":"Press Release"}]},{"@type":"WebSite","@id":"https:\/\/maslabor.com\/#website","url":"https:\/\/maslabor.com\/","name":"m\u00e1sLabor","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maslabor.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/maslabor.com\/es\/wp-json\/wp\/v2\/categories\/80","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maslabor.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/maslabor.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/maslabor.com\/es\/wp-json\/wp\/v2\/posts?categories=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}